{"id":10,"date":"2023-08-07T12:42:34","date_gmt":"2023-08-07T10:42:34","guid":{"rendered":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/?page_id=10"},"modified":"2023-08-23T16:38:54","modified_gmt":"2023-08-23T14:38:54","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">1. Datenschutz auf einen Blick<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise<\/h3>\n\n\n\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Datenerfassung auf dieser Website<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/h4>\n\n\n\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wie erfassen wir Ihre Daten?<\/h4>\n\n\n\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.&nbsp;B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n\n\n\n<p>Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.&nbsp;B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Wof\u00fcr nutzen wir Ihre Daten?<\/h4>\n\n\n\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h4>\n\n\n\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n\n\n\n<p>Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Hosting<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Strato<\/h3>\n\n\n\n<p>Wir hosten unsere Website bei Strato. Anbieter ist die Strato AG, Pascalstra\u00dfe 10, 10587 Berlin (nachfolgend: \u201eStrato\u201c). Wenn Sie unsere Website besuchen, erfasst Strato verschiedene Logfiles inklusive Ihrer IP-Adressen.<\/p>\n\n\n\n<p>Weitere Informationen entnehmen Sie der Datenschutzerkl\u00e4rung von Strato:&nbsp;<a href=\"https:\/\/www.strato.de\/datenschutz\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.strato.de\/datenschutz\/<\/a>.<\/p>\n\n\n\n<p>Die Verwendung von Strato erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an einer m\u00f6glichst zuverl\u00e4ssigen Darstellung unserer Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Allgemeine Hinweise und Pflicht\u00adinformationen<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Datenschutz<\/h3>\n\n\n\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n\n\n\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n\n\n\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.&nbsp;B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweis zur verantwortlichen Stelle<\/h3>\n\n\n\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n\n\n\n<p>apetito catering B.V. & Co. KG<br>Gesch\u00e4ftsf\u00fchrer: Andreas Oellerich<br>Bonifatiusstra\u00dfe 305<br>48432 Rheine<\/p>\n\n\n\n<p>Telefon: +49 5971 799-0<br>E-Mail: datenschutz-catering@apetito.de<\/p>\n\n\n\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.&nbsp;B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Speicherdauer<\/h3>\n\n\n\n<p>Soweit innerhalb dieser Datenschutzerkl\u00e4rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Wenn Sie ein berechtigtes L\u00f6schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel\u00f6scht, sofern wir keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten haben (z.&nbsp;B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L\u00f6schung nach Fortfall dieser Gr\u00fcnde.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Allgemeine Hinweise zu den Rechtsgrundlagen der Datenverarbeitung auf dieser Website<\/h3>\n\n\n\n<p>Sofern Sie in die Datenverarbeitung eingewilligt haben, verarbeiten wir Ihre personenbezogenen Daten auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO bzw. Art. 9 Abs. 2 lit. a DSGVO, sofern besondere Datenkategorien nach Art. 9 Abs. 1 DSGVO verarbeitet werden. Sofern Sie in die Speicherung von Cookies oder in den Zugriff auf Informationen in Ihr Endger\u00e4t (z.&nbsp;B. via Device-Fingerprinting) eingewilligt haben, erfolgt die Datenverarbeitung zus\u00e4tzlich auf Grundlage von \u00a7 25 Abs. 1 TTDSG. Die Einwilligung ist jederzeit widerrufbar. Sind Ihre Daten zur Vertragserf\u00fcllung oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, verarbeiten wir Ihre Daten auf Grundlage des Art. 6 Abs. 1 lit. b DSGVO. Des Weiteren verarbeiten wir Ihre Daten, sofern diese zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich sind auf Grundlage von Art. 6 Abs. 1 lit. c DSGVO. Die Datenverarbeitung kann ferner auf Grundlage unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO erfolgen. \u00dcber die jeweils im Einzelfall einschl\u00e4gigen Rechtsgrundlagen wird in den folgenden Abs\u00e4tzen dieser Datenschutzerkl\u00e4rung informiert.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hinweis zur Datenweitergabe in die USA und sonstige Drittstaaten<\/h3>\n\n\n\n<p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in den USA oder sonstigen datenschutzrechtlich nicht sicheren Drittstaaten. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogene Daten in diese Drittstaaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in diesen L\u00e4ndern kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann. Beispielsweise sind US-Unternehmen dazu verpflichtet, personenbezogene Daten an Sicherheitsbeh\u00f6rden herauszugeben, ohne dass Sie als Betroffener hiergegen gerichtlich vorgehen k\u00f6nnten. Es kann daher nicht ausgeschlossen werden, dass US-Beh\u00f6rden (z.&nbsp;B. Geheimdienste) Ihre auf US-Servern befindlichen Daten zu \u00dcberwachungszwecken verarbeiten, auswerten und dauerhaft speichern. Wir haben auf diese Verarbeitungst\u00e4tigkeiten keinen Einfluss.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n\n\n\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n\n\n\n<p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p>\n\n\n\n<p>WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beschwerde\u00adrecht bei der zust\u00e4ndigen Aufsichts\u00adbeh\u00f6rde<\/h3>\n\n\n\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Daten\u00ad\u00fcbertrag\u00adbarkeit<\/h3>\n\n\n\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n\n\n\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n\n\n\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auskunft, L\u00f6schung und Berichtigung<\/h3>\n\n\n\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n\n\n\n<p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n\n\n\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n\n\n\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n\n\n\n<p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Widerspruch gegen Werbe-E-Mails<\/h3>\n\n\n\n<p>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Datenerfassung auf dieser Website<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Server-Log-Dateien<\/h3>\n\n\n\n<p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Browsertyp und Browserversion<\/li>\n\n\n\n<li>verwendetes Betriebssystem<\/li>\n\n\n\n<li>Referrer URL<\/li>\n\n\n\n<li>Hostname des zugreifenden Rechners<\/li>\n\n\n\n<li>Uhrzeit der Serveranfrage<\/li>\n\n\n\n<li>IP-Adresse<\/li>\n<\/ul>\n\n\n\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n\n\n\n<p>Die Erfassung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung seiner Website \u2013 hierzu m\u00fcssen die Server-Log-Files erfasst werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anfrage per E-Mail, Telefon oder Telefax<\/h3>\n\n\n\n<p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n\n\n\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde.<\/p>\n\n\n\n<p>Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.&nbsp;B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>ANSPRECHPARTNER F\u00dcR DEN DATENSCHUTZ<\/strong><\/h4>\n\n\n\n<p>Sollten Sie Fragen oder Anmerkungen zum Datenschutz haben oder der Verwendung Ihrer personenbezogenen Daten zum Zwecke der Werbung, der Markt- oder Meinungsforschung widersprechen wollen, schreiben Sie bitte an unseren Datenschutzbeauftragten Herrn Norbert Schl\u00e4tker, E-Mail: Datenschutz-catering(at)apetito.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wp-custom-template-legal","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - apetito | BACK TO THE STREET<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - apetito | BACK TO THE STREET\" \/>\n<meta property=\"og:description\" content=\"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"apetito | BACK TO THE STREET\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-23T14:38:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/datenschutz\\\/\",\"name\":\"Datenschutz - apetito | BACK TO THE STREET\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/#website\"},\"datePublished\":\"2023-08-07T10:42:34+00:00\",\"dateModified\":\"2023-08-23T14:38:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/datenschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/#website\",\"url\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/\",\"name\":\"apetito | BACK TO THE STREET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/#organization\",\"name\":\"apetito\",\"url\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo-acKontur.svg\",\"contentUrl\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Logo-acKontur.svg\",\"caption\":\"apetito\"},\"image\":{\"@id\":\"https:\\\/\\\/www.apetito-catering.de\\\/aktion\\\/back-to-the-street\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - apetito | BACK TO THE STREET","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - apetito | BACK TO THE STREET","og_description":"1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser Website [&hellip;]","og_url":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/","og_site_name":"apetito | BACK TO THE STREET","article_modified_time":"2023-08-23T14:38:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/","url":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/","name":"Datenschutz - apetito | BACK TO THE STREET","isPartOf":{"@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/#website"},"datePublished":"2023-08-07T10:42:34+00:00","dateModified":"2023-08-23T14:38:54+00:00","breadcrumb":{"@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/#website","url":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/","name":"apetito | BACK TO THE STREET","description":"","publisher":{"@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/#organization","name":"apetito","url":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/#\/schema\/logo\/image\/","url":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-content\/uploads\/2024\/03\/Logo-acKontur.svg","contentUrl":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-content\/uploads\/2024\/03\/Logo-acKontur.svg","caption":"apetito"},"image":{"@id":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":2,"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":198,"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/pages\/10\/revisions\/198"}],"wp:attachment":[{"href":"https:\/\/www.apetito-catering.de\/aktion\/back-to-the-street\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}